{"id":19817,"date":"2018-01-16T17:36:31","date_gmt":"2018-01-16T16:36:31","guid":{"rendered":"http:\/\/www.info-algerie.com\/actualites\/projet-de-loi-sur-les-collectivites-locales-approfondir-la-decentralisation-elargir-les-prerogatives-des-assemblees-elues\/"},"modified":"2018-01-16T17:36:31","modified_gmt":"2018-01-16T16:36:31","slug":"projet-de-loi-sur-les-collectivites-locales-approfondir-la-decentralisation-elargir-les-prerogatives-des-assemblees-elues","status":"publish","type":"post","link":"https:\/\/www.info-algerie.com\/actualites\/projet-de-loi-sur-les-collectivites-locales-approfondir-la-decentralisation-elargir-les-prerogatives-des-assemblees-elues\/","title":{"rendered":"Projet de loi sur les collectivit\u00e9s locales: approfondir la d\u00e9centralisation, \u00e9largir les pr\u00e9rogatives des assembl\u00e9es \u00e9lues"},"content":{"rendered":"<div class=\"K2FeedImage\"><img decoding=\"async\" src=\"https:\/\/www.info-algerie.com\/actualites\/wp-content\/uploads\/2018\/01\/b585557ebe330b90382644c5f0d9faae_S.jpg\" alt=\"Projet de loi sur les collectivit&#xE9;s locales: approfondir la d&#xE9;centralisation, &#xE9;largir les pr&#xE9;rogatives des assembl&#xE9;es &#xE9;lues\" \/><\/div>\n<div class=\"K2FeedIntroText\">\n<p><strong>ALGER &#8211; L&rsquo;inspecteur g\u00e9n\u00e9ral du minist\u00e8re de l&rsquo;Int\u00e9rieur, des Collectivit\u00e9s locales et de l&rsquo;Am\u00e9nagement du territoire, Abderrahmane Sedini a affirm\u00e9, mardi \u00e0 Alger, que le projet de loi relatif aux collectivit\u00e9s locales, en \u00e9laboration, va approfondir la d\u00e9centralisation et \u00e9largir les pr\u00e9rogatives des assembl\u00e9es \u00e9lues en vue de permettre aux communes de r\u00e9aliser le d\u00e9veloppement local et prendre en charge les pr\u00e9occupations des citoyens.<\/strong><\/p>\n<p>&#013;\n<\/p><\/div>\n<div class=\"K2FeedFullText\">&#013;<\/p>\n<p>Dans un entretien \u00e0 l&rsquo;APS \u00e0 la veille de la c\u00e9l\u00e9bration de la 51e journ\u00e9e nationale de la Commune, co\u00efncidant avec la promulgation du premier Code communal le 18 janvier 1967, M. Sedini a pr\u00e9cis\u00e9 que la commune \u00ab\u00a0continuera \u00e0 accomplir des r\u00e9alisations \u00e0 la faveur du contenu du projet pr\u00e9liminaire relatif au code des collectivit\u00e9s locales qui garantira toutes les nouvelles valeurs constitutionnelles, notamment le renforcement du r\u00f4le des collectivit\u00e9s locales, l&rsquo;approfondissement de la d\u00e9centralisation, l&rsquo;\u00e9largissement des pr\u00e9rogatives des assembl\u00e9es \u00e9lues, la promotion de la d\u00e9mocratie participative\u00a0\u00bb.<\/p>\n<p>&#013;<\/p>\n<hr \/>\n<p>Lire aussi:\u00a0<a href=\"http:\/\/www.aps.dz\/algerie\/60560-le-ministre-de-l-interieur-annonce-un-projet-de-loi-relative-aux-collectivites-territoriales\" target=\"_blank\" rel=\"noopener noreferrer\">Le ministre de l&rsquo;Int\u00e9rieur annonce un projet de loi relative aux collectivit\u00e9s territoriales<\/a><\/p>\n<p>&#013;<\/p>\n<hr \/>\n<p>Il s&rsquo;agit en outre de \u00ab\u00a0consacrer les principes des bonnes pratiques en mati\u00e8re de gouvernance locale, d&rsquo;activer le nouveau r\u00f4le \u00e9conomique de la commune et instituer un nouveau syst\u00e8me de fiscalit\u00e9 locale\u00a0\u00bb, a-t-il expliqu\u00e9.<\/p>\n<p>&#013;<\/p>\n<p>Faisant \u00e9tat de \u00ab\u00a0propositions\u00a0\u00bb sur le projet de loi \u00ab\u00a0en cours d&rsquo;\u00e9laboration\u00a0\u00bb, formul\u00e9es par toutes les wilayas \u00e0 travers des groupes de r\u00e9flexion, le m\u00eame responsable a indiqu\u00e9 que de larges consultations seront \u00ab\u00a0ouvertes avec les diff\u00e9rentes parties en relation avec la commune\u00a0\u00bb pour son enrichissement\u00a0\u00bb.<\/p>\n<p>&#013;<\/p>\n<p>Evoquant les importantes \u00ab\u00a0r\u00e9alisations\u00a0\u00bb qu&rsquo;a connues la commune ces derni\u00e8res ann\u00e9es, il a cit\u00e9 notamment la num\u00e9risation de toutes les communes et leurs annexes et leur dotation en syst\u00e8mes informatiques modernes, ce qui a permis, a-t-il dit,\u00a0 \u00ab\u00a0d&rsquo;acc\u00e9l\u00e9rer et d&rsquo;am\u00e9liorer les prestations et r\u00e9duire la bureaucratie\u00a0\u00bb.<\/p>\n<p>&#013;<\/p>\n<p>La lutte contre la bureaucratie au niveau des services communaux est un \u00ab\u00a0travail quotidien et constant\u00a0\u00bb, a affirm\u00e9 M. Sidini relevant une \u00ab\u00a0am\u00e9lioration notable\u00a0\u00bb gr\u00e2ce aux m\u00e9canismes modernes bas\u00e9s sur les nouveaux supports informatiques outre les \u00ab\u00a0missions d&rsquo;inspection et de contr\u00f4le\u00a0\u00bb effectu\u00e9es sur l&rsquo;ensembles des communes du territoire national.<\/p>\n<p>&#013;<\/p>\n<p>Il a fait savoir, dans ce sens, que plusieurs faits bureaucratiques \u00ab\u00a0ont \u00e9t\u00e9 trait\u00e9s \u00e0 temps et des mesures prises \u00e0 l&rsquo;encontre les contrevenants\u00a0\u00bb.<\/p>\n<p>&#013;<\/p>\n<p>M. Sedini a indiqu\u00e9 que le num\u00e9ro vert (1100) lanc\u00e9 par le minist\u00e8re enregistre quotidiennement les dol\u00e9ances et pr\u00e9occupations des citoyens qui sont orient\u00e9s vers les services concern\u00e9s pour leur prise en charge.<\/p>\n<p>&#013;<\/p>\n<p>Il a fait \u00e9tat, par ailleurs, d&rsquo;une \u00ab\u00a0r\u00e9flexion au niveau du minist\u00e8re pour prolonger les heures de travail l\u00e9gales dans les communes\u00a0\u00bb, \u00e0 l&rsquo;instar d&rsquo;initiatives \u00e9manant de plusieurs communes telle que la commune d&rsquo;Alger centre ainsi que la possibilit\u00e9 d&rsquo;ouverture des communes ou de leurs annexes pendant les jours f\u00e9ri\u00e9s\u00a0\u00bb.<\/p>\n<p>&#013;<\/p>\n<hr \/>\n<h3>Lire aussi:\u00a0<a href=\"http:\/\/www.aps.dz\/algerie\/68447-rencontre-nationale-des-presidents-d-apw-et-d-apc-jeudi-prochain\" target=\"_blank\" rel=\"noopener noreferrer\">Rencontre nationale des pr\u00e9sidents d&rsquo;APW et d&rsquo;APC jeudi prochain\u00a0<\/a><\/h3>\n<p>&#013;<\/p>\n<hr \/>\n<p>Apr\u00e8s avoir rappel\u00e9 l&rsquo;installation de l&rsquo;ensemble les assembl\u00e9es populaires communales et de wilaya (APC\/APW) issues des locales du 23 novembre dernier, M. Sedini a indiqu\u00e9 que de \u00ab\u00a0grandes \u00e9tapes ont \u00e9t\u00e9 franchies dans la gestion des communes gr\u00e2ce aux capacit\u00e9s des ressources humaines et leurs initiatives enrichissantes\u00a0\u00bb, ajoutant que plus de 4.000 APC et 586 APW sont issues des derni\u00e8res \u00e9lections locales.<\/p>\n<p>&#013;<\/p>\n<p>Evaluant les conventions de jumelage \u00e9tablies entre certaines communes du pays et leurs homologues \u00e9trang\u00e8res, le m\u00eame responsable a affirm\u00e9 que ces exp\u00e9riences \u00e9taient \u00ab\u00a0fructueuses\u00a0\u00bb d&rsquo;autant qu&rsquo;elles ont permis la \u00ab\u00a0concr\u00e9tisations de plusieurs id\u00e9es de coop\u00e9ration tout en tirant profit des exp\u00e9riences et des techniques en mati\u00e8re de gestion locale\u00a0\u00bb.<\/p>\n<p>&#013;<\/p>\n<p>Concernant les contractuels des communes, Il a indiqu\u00e9 que plusieurs jeunes ont \u00e9t\u00e9 ins\u00e9r\u00e9s dans des postes permanents, assurant que cette op\u00e9ration se poursuivra graduellement chaque ann\u00e9e, selon le nombre de postes de travail ouverts et conform\u00e9ment aux lois en vigueur\u00a0\u00bb.<\/p>\n<p>&#013;<\/p>\n<p>Par ailleurs, M. Sadini a affirm\u00e9 que \u00ab\u00a0les \u00e9quipes charg\u00e9es de d\u00e9livrer le permis de conduire et la carte d&rsquo;immatriculation des v\u00e9hicules \u00e9lectroniques \u0153uvrent activement pour que ces documents soient d\u00e9livr\u00e9s durant le premier trimestre de l&rsquo;ann\u00e9e en cours\u00a0\u00bb.<\/p>\n<p>&#013;<\/p>\n<p>Dans le cadre des festivit\u00e9s c\u00e9l\u00e9brant la journ\u00e9e nationale de la commune, M. Sadini a indiqu\u00e9 que le ministre de l&rsquo;Int\u00e9rieur, des collectivit\u00e9s locales et de l&rsquo;am\u00e9nagement du territoire, Noureddine Bedoui pr\u00e9sidera jeudi prochain une r\u00e9union nationale d&rsquo;orientation regroupant les APC et APW pour mettre en avant les grands chapitres de la strat\u00e9gie devant \u00eatre suivie par les \u00e9lus locaux en vue de relancer le d\u00e9veloppement local.<\/p>\n<p>&#013;<\/p>\n<p>La rencontre permettra, selon M. Sadini, de mettre l&rsquo;accent sur \u00ab\u00a0la poursuite de l&rsquo;am\u00e9lioration du fonctionnement des services de la commune\u00a0\u00bb, notamment \u00ab\u00a0l&rsquo;activation de la fonction \u00e9conomique\u00a0\u00bb de la commune, outre \u00ab\u00a0l&rsquo;attachement aux nouveaux principes du d\u00e9veloppement local durable bas\u00e9s sur l&rsquo;utilisation des \u00e9nergies favorables \u00e0 l&rsquo;environnement\u00a0\u00bb, et l&rsquo;acc\u00e9l\u00e9ration du processus de modernisation des services communaux et des infrastructures publiques.<\/p>\n<p>&#013;<\/p>\n<p>\u00ab\u00a0A l&rsquo;occasion de la Journ\u00e9e Nationale de la Commune, un programme \u00ab\u00a0riche\u00a0\u00bb sera mis en place au niveau de la commune de Baraki (\u00e0 l&rsquo;ouest d&rsquo;Alger), mercredi prochain. Le choix de cette commune est dict\u00e9 par des consid\u00e9rations \u00ab\u00a0symboliques\u00a0\u00bb notamment les sacrifices \u00e9normes qu&rsquo;elle a consentis au cours de la d\u00e9cennie noire\u00a0\u00bb outre le fait qu&rsquo;elle symbolise la r\u00e9ussite de la Charte de paix et de r\u00e9conciliation nationales\u00a0\u00bb initi\u00e9e par le pr\u00e9sident de la R\u00e9publique, Abdelaziz Bouteflika en 2005.<\/p>\n<p>&#013;<\/p>\n<p>M. Sedini a ajout\u00e9 qu&rsquo;il sera proc\u00e9d\u00e9, \u00e0 cette occasion, au \u00ab\u00a0lancement\u00a0\u00bb du service du guichet \u00e9lectronique unique au niveau de la commune de Baraki et \u00e0 l&rsquo;inspection de plusieurs structures au niveau du quartier de Ben Talha qui \u00ab\u00a0a v\u00e9cu des \u00e9v\u00e8nements dramatiques dans les ann\u00e9es 90 et qui est aujourd&rsquo;hui un bel exemple de d\u00e9veloppement \u00ab\u00a0gr\u00e2ce aux diff\u00e9rents plans de d\u00e9veloppement.<\/p>\n<\/div>\n<p>&#013;<br \/>\nSource: <a href=\"http:\/\/www.aps.dz\/algerie\/68475-projet-de-loi-sur-les-collectivites-locales-approfondir-la-decentralisation-elargir-les-prerogatives-des-assemblees-elues\" target=\"_blank\">Projet de loi sur les collectivit\u00e9s locales: approfondir la d\u00e9centralisation, \u00e9largir les pr\u00e9rogatives des assembl\u00e9es \u00e9lues<\/a><\/p>\n<!--CusAds0-->\n<div style=\"font-size: 0px; height: 0px; line-height: 0px; margin: 0; padding: 0; clear: both;\"><\/div>","protected":false},"excerpt":{"rendered":"<p>ALGER &#8211; L&rsquo;inspecteur g\u00e9n\u00e9ral du minist\u00e8re de l&rsquo;Int\u00e9rieur, des Collectivit\u00e9s locales et de l&rsquo;Am\u00e9nagement du territoire, Abderrahmane Sedini a affirm\u00e9, mardi \u00e0 Alger, que le projet de loi relatif aux collectivit\u00e9s locales, en \u00e9laboration, va approfondir la d\u00e9centralisation et \u00e9largir les pr\u00e9rogatives des assembl\u00e9es \u00e9lues en vue de permettre aux communes de r\u00e9aliser le d\u00e9veloppement<\/p>\n","protected":false},"author":6,"featured_media":19818,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22],"tags":[93],"class_list":["post-19817","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-infos","tag-onu"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Projet de loi sur les collectivit\u00e9s locales: approfondir la d\u00e9centralisation, \u00e9largir les pr\u00e9rogatives des assembl\u00e9es \u00e9lues - info algerie<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.info-algerie.com\/actualites\/projet-de-loi-sur-les-collectivites-locales-approfondir-la-decentralisation-elargir-les-prerogatives-des-assemblees-elues\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Projet de loi sur les collectivit\u00e9s locales: approfondir la d\u00e9centralisation, \u00e9largir les pr\u00e9rogatives des assembl\u00e9es \u00e9lues - info algerie\" \/>\n<meta property=\"og:description\" content=\"ALGER &#8211; L&rsquo;inspecteur g\u00e9n\u00e9ral du minist\u00e8re de l&rsquo;Int\u00e9rieur, des Collectivit\u00e9s locales et de l&rsquo;Am\u00e9nagement du territoire, Abderrahmane Sedini a affirm\u00e9, mardi \u00e0 Alger, que le projet de loi relatif aux collectivit\u00e9s locales, en \u00e9laboration, va approfondir la d\u00e9centralisation et \u00e9largir les pr\u00e9rogatives des assembl\u00e9es \u00e9lues en vue de permettre aux communes de r\u00e9aliser le d\u00e9veloppement\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.info-algerie.com\/actualites\/projet-de-loi-sur-les-collectivites-locales-approfondir-la-decentralisation-elargir-les-prerogatives-des-assemblees-elues\/\" \/>\n<meta property=\"og:site_name\" content=\"info algerie\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/infoalgerieactu\" \/>\n<meta property=\"article:published_time\" content=\"2018-01-16T16:36:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.info-algerie.com\/actualites\/wp-content\/uploads\/2018\/01\/b585557ebe330b90382644c5f0d9faae_S-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"280\" \/>\n\t<meta property=\"og:image:height\" content=\"169\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"La r\u00e9daction\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"La r\u00e9daction\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.info-algerie.com\\\/actualites\\\/projet-de-loi-sur-les-collectivites-locales-approfondir-la-decentralisation-elargir-les-prerogatives-des-assemblees-elues\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.info-algerie.com\\\/actualites\\\/projet-de-loi-sur-les-collectivites-locales-approfondir-la-decentralisation-elargir-les-prerogatives-des-assemblees-elues\\\/\"},\"author\":{\"name\":\"La r\u00e9daction\",\"@id\":\"https:\\\/\\\/www.info-algerie.com\\\/actualites\\\/#\\\/schema\\\/person\\\/847aaec44920825b843a08f30ec6aa1e\"},\"headline\":\"Projet de loi sur les collectivit\u00e9s locales: approfondir la d\u00e9centralisation, \u00e9largir les pr\u00e9rogatives des assembl\u00e9es \u00e9lues\",\"datePublished\":\"2018-01-16T16:36:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.info-algerie.com\\\/actualites\\\/projet-de-loi-sur-les-collectivites-locales-approfondir-la-decentralisation-elargir-les-prerogatives-des-assemblees-elues\\\/\"},\"wordCount\":1109,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.info-algerie.com\\\/actualites\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.info-algerie.com\\\/actualites\\\/projet-de-loi-sur-les-collectivites-locales-approfondir-la-decentralisation-elargir-les-prerogatives-des-assemblees-elues\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.info-algerie.com\\\/actualites\\\/wp-content\\\/uploads\\\/2018\\\/01\\\/b585557ebe330b90382644c5f0d9faae_S-1.jpg\",\"keywords\":[\"ONU\"],\"articleSection\":[\"infos\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.info-algerie.com\\\/actualites\\\/projet-de-loi-sur-les-collectivites-locales-approfondir-la-decentralisation-elargir-les-prerogatives-des-assemblees-elues\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.info-algerie.com\\\/actualites\\\/projet-de-loi-sur-les-collectivites-locales-approfondir-la-decentralisation-elargir-les-prerogatives-des-assemblees-elues\\\/\",\"url\":\"https:\\\/\\\/www.info-algerie.com\\\/actualites\\\/projet-de-loi-sur-les-collectivites-locales-approfondir-la-decentralisation-elargir-les-prerogatives-des-assemblees-elues\\\/\",\"name\":\"Projet de loi sur les collectivit\u00e9s locales: approfondir la d\u00e9centralisation, \u00e9largir les pr\u00e9rogatives des assembl\u00e9es \u00e9lues - info algerie\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.info-algerie.com\\\/actualites\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.info-algerie.com\\\/actualites\\\/projet-de-loi-sur-les-collectivites-locales-approfondir-la-decentralisation-elargir-les-prerogatives-des-assemblees-elues\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.info-algerie.com\\\/actualites\\\/projet-de-loi-sur-les-collectivites-locales-approfondir-la-decentralisation-elargir-les-prerogatives-des-assemblees-elues\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.info-algerie.com\\\/actualites\\\/wp-content\\\/uploads\\\/2018\\\/01\\\/b585557ebe330b90382644c5f0d9faae_S-1.jpg\",\"datePublished\":\"2018-01-16T16:36:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.info-algerie.com\\\/actualites\\\/projet-de-loi-sur-les-collectivites-locales-approfondir-la-decentralisation-elargir-les-prerogatives-des-assemblees-elues\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.info-algerie.com\\\/actualites\\\/projet-de-loi-sur-les-collectivites-locales-approfondir-la-decentralisation-elargir-les-prerogatives-des-assemblees-elues\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.info-algerie.com\\\/actualites\\\/projet-de-loi-sur-les-collectivites-locales-approfondir-la-decentralisation-elargir-les-prerogatives-des-assemblees-elues\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.info-algerie.com\\\/actualites\\\/wp-content\\\/uploads\\\/2018\\\/01\\\/b585557ebe330b90382644c5f0d9faae_S-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.info-algerie.com\\\/actualites\\\/wp-content\\\/uploads\\\/2018\\\/01\\\/b585557ebe330b90382644c5f0d9faae_S-1.jpg\",\"width\":280,\"height\":169},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.info-algerie.com\\\/actualites\\\/projet-de-loi-sur-les-collectivites-locales-approfondir-la-decentralisation-elargir-les-prerogatives-des-assemblees-elues\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.info-algerie.com\\\/actualites\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Projet de loi sur les collectivit\u00e9s locales: approfondir la d\u00e9centralisation, \u00e9largir les pr\u00e9rogatives des assembl\u00e9es \u00e9lues\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.info-algerie.com\\\/actualites\\\/#website\",\"url\":\"https:\\\/\\\/www.info-algerie.com\\\/actualites\\\/\",\"name\":\"info algerie\",\"description\":\"Toutes les actualit\u00e9s\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.info-algerie.com\\\/actualites\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.info-algerie.com\\\/actualites\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.info-algerie.com\\\/actualites\\\/#organization\",\"name\":\"info algerie\",\"url\":\"https:\\\/\\\/www.info-algerie.com\\\/actualites\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.info-algerie.com\\\/actualites\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.info-algerie.com\\\/actualites\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/logo-ia-120.png\",\"contentUrl\":\"https:\\\/\\\/www.info-algerie.com\\\/actualites\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/logo-ia-120.png\",\"width\":120,\"height\":43,\"caption\":\"info algerie\"},\"image\":{\"@id\":\"https:\\\/\\\/www.info-algerie.com\\\/actualites\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/infoalgerieactu\",\"https:\\\/\\\/x.com\\\/infoalgerie1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.info-algerie.com\\\/actualites\\\/#\\\/schema\\\/person\\\/847aaec44920825b843a08f30ec6aa1e\",\"name\":\"La r\u00e9daction\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/769db425c6f465158149f1ffd6cf61ce7a8a879d11dfbef8288af36dfddd418c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/769db425c6f465158149f1ffd6cf61ce7a8a879d11dfbef8288af36dfddd418c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/769db425c6f465158149f1ffd6cf61ce7a8a879d11dfbef8288af36dfddd418c?s=96&d=mm&r=g\",\"caption\":\"La r\u00e9daction\"},\"sameAs\":[\"http:\\\/\\\/www.lkeria.com\\\/\"],\"url\":\"https:\\\/\\\/www.info-algerie.com\\\/actualites\\\/author\\\/chakib32\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Projet de loi sur les collectivit\u00e9s locales: approfondir la d\u00e9centralisation, \u00e9largir les pr\u00e9rogatives des assembl\u00e9es \u00e9lues - info algerie","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.info-algerie.com\/actualites\/projet-de-loi-sur-les-collectivites-locales-approfondir-la-decentralisation-elargir-les-prerogatives-des-assemblees-elues\/","og_locale":"fr_FR","og_type":"article","og_title":"Projet de loi sur les collectivit\u00e9s locales: approfondir la d\u00e9centralisation, \u00e9largir les pr\u00e9rogatives des assembl\u00e9es \u00e9lues - info algerie","og_description":"ALGER &#8211; L&rsquo;inspecteur g\u00e9n\u00e9ral du minist\u00e8re de l&rsquo;Int\u00e9rieur, des Collectivit\u00e9s locales et de l&rsquo;Am\u00e9nagement du territoire, Abderrahmane Sedini a affirm\u00e9, mardi \u00e0 Alger, que le projet de loi relatif aux collectivit\u00e9s locales, en \u00e9laboration, va approfondir la d\u00e9centralisation et \u00e9largir les pr\u00e9rogatives des assembl\u00e9es \u00e9lues en vue de permettre aux communes de r\u00e9aliser le d\u00e9veloppement","og_url":"https:\/\/www.info-algerie.com\/actualites\/projet-de-loi-sur-les-collectivites-locales-approfondir-la-decentralisation-elargir-les-prerogatives-des-assemblees-elues\/","og_site_name":"info algerie","article_publisher":"https:\/\/www.facebook.com\/infoalgerieactu","article_published_time":"2018-01-16T16:36:31+00:00","og_image":[{"width":280,"height":169,"url":"https:\/\/www.info-algerie.com\/actualites\/wp-content\/uploads\/2018\/01\/b585557ebe330b90382644c5f0d9faae_S-1.jpg","type":"image\/jpeg"}],"author":"La r\u00e9daction","twitter_misc":{"\u00c9crit par":"La r\u00e9daction","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.info-algerie.com\/actualites\/projet-de-loi-sur-les-collectivites-locales-approfondir-la-decentralisation-elargir-les-prerogatives-des-assemblees-elues\/#article","isPartOf":{"@id":"https:\/\/www.info-algerie.com\/actualites\/projet-de-loi-sur-les-collectivites-locales-approfondir-la-decentralisation-elargir-les-prerogatives-des-assemblees-elues\/"},"author":{"name":"La r\u00e9daction","@id":"https:\/\/www.info-algerie.com\/actualites\/#\/schema\/person\/847aaec44920825b843a08f30ec6aa1e"},"headline":"Projet de loi sur les collectivit\u00e9s locales: approfondir la d\u00e9centralisation, \u00e9largir les pr\u00e9rogatives des assembl\u00e9es \u00e9lues","datePublished":"2018-01-16T16:36:31+00:00","mainEntityOfPage":{"@id":"https:\/\/www.info-algerie.com\/actualites\/projet-de-loi-sur-les-collectivites-locales-approfondir-la-decentralisation-elargir-les-prerogatives-des-assemblees-elues\/"},"wordCount":1109,"commentCount":0,"publisher":{"@id":"https:\/\/www.info-algerie.com\/actualites\/#organization"},"image":{"@id":"https:\/\/www.info-algerie.com\/actualites\/projet-de-loi-sur-les-collectivites-locales-approfondir-la-decentralisation-elargir-les-prerogatives-des-assemblees-elues\/#primaryimage"},"thumbnailUrl":"https:\/\/www.info-algerie.com\/actualites\/wp-content\/uploads\/2018\/01\/b585557ebe330b90382644c5f0d9faae_S-1.jpg","keywords":["ONU"],"articleSection":["infos"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.info-algerie.com\/actualites\/projet-de-loi-sur-les-collectivites-locales-approfondir-la-decentralisation-elargir-les-prerogatives-des-assemblees-elues\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.info-algerie.com\/actualites\/projet-de-loi-sur-les-collectivites-locales-approfondir-la-decentralisation-elargir-les-prerogatives-des-assemblees-elues\/","url":"https:\/\/www.info-algerie.com\/actualites\/projet-de-loi-sur-les-collectivites-locales-approfondir-la-decentralisation-elargir-les-prerogatives-des-assemblees-elues\/","name":"Projet de loi sur les collectivit\u00e9s locales: approfondir la d\u00e9centralisation, \u00e9largir les pr\u00e9rogatives des assembl\u00e9es \u00e9lues - info algerie","isPartOf":{"@id":"https:\/\/www.info-algerie.com\/actualites\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.info-algerie.com\/actualites\/projet-de-loi-sur-les-collectivites-locales-approfondir-la-decentralisation-elargir-les-prerogatives-des-assemblees-elues\/#primaryimage"},"image":{"@id":"https:\/\/www.info-algerie.com\/actualites\/projet-de-loi-sur-les-collectivites-locales-approfondir-la-decentralisation-elargir-les-prerogatives-des-assemblees-elues\/#primaryimage"},"thumbnailUrl":"https:\/\/www.info-algerie.com\/actualites\/wp-content\/uploads\/2018\/01\/b585557ebe330b90382644c5f0d9faae_S-1.jpg","datePublished":"2018-01-16T16:36:31+00:00","breadcrumb":{"@id":"https:\/\/www.info-algerie.com\/actualites\/projet-de-loi-sur-les-collectivites-locales-approfondir-la-decentralisation-elargir-les-prerogatives-des-assemblees-elues\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.info-algerie.com\/actualites\/projet-de-loi-sur-les-collectivites-locales-approfondir-la-decentralisation-elargir-les-prerogatives-des-assemblees-elues\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.info-algerie.com\/actualites\/projet-de-loi-sur-les-collectivites-locales-approfondir-la-decentralisation-elargir-les-prerogatives-des-assemblees-elues\/#primaryimage","url":"https:\/\/www.info-algerie.com\/actualites\/wp-content\/uploads\/2018\/01\/b585557ebe330b90382644c5f0d9faae_S-1.jpg","contentUrl":"https:\/\/www.info-algerie.com\/actualites\/wp-content\/uploads\/2018\/01\/b585557ebe330b90382644c5f0d9faae_S-1.jpg","width":280,"height":169},{"@type":"BreadcrumbList","@id":"https:\/\/www.info-algerie.com\/actualites\/projet-de-loi-sur-les-collectivites-locales-approfondir-la-decentralisation-elargir-les-prerogatives-des-assemblees-elues\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.info-algerie.com\/actualites\/"},{"@type":"ListItem","position":2,"name":"Projet de loi sur les collectivit\u00e9s locales: approfondir la d\u00e9centralisation, \u00e9largir les pr\u00e9rogatives des assembl\u00e9es \u00e9lues"}]},{"@type":"WebSite","@id":"https:\/\/www.info-algerie.com\/actualites\/#website","url":"https:\/\/www.info-algerie.com\/actualites\/","name":"info algerie","description":"Toutes les actualit\u00e9s","publisher":{"@id":"https:\/\/www.info-algerie.com\/actualites\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.info-algerie.com\/actualites\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.info-algerie.com\/actualites\/#organization","name":"info algerie","url":"https:\/\/www.info-algerie.com\/actualites\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.info-algerie.com\/actualites\/#\/schema\/logo\/image\/","url":"https:\/\/www.info-algerie.com\/actualites\/wp-content\/uploads\/2022\/07\/logo-ia-120.png","contentUrl":"https:\/\/www.info-algerie.com\/actualites\/wp-content\/uploads\/2022\/07\/logo-ia-120.png","width":120,"height":43,"caption":"info algerie"},"image":{"@id":"https:\/\/www.info-algerie.com\/actualites\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/infoalgerieactu","https:\/\/x.com\/infoalgerie1"]},{"@type":"Person","@id":"https:\/\/www.info-algerie.com\/actualites\/#\/schema\/person\/847aaec44920825b843a08f30ec6aa1e","name":"La r\u00e9daction","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/769db425c6f465158149f1ffd6cf61ce7a8a879d11dfbef8288af36dfddd418c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/769db425c6f465158149f1ffd6cf61ce7a8a879d11dfbef8288af36dfddd418c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/769db425c6f465158149f1ffd6cf61ce7a8a879d11dfbef8288af36dfddd418c?s=96&d=mm&r=g","caption":"La r\u00e9daction"},"sameAs":["http:\/\/www.lkeria.com\/"],"url":"https:\/\/www.info-algerie.com\/actualites\/author\/chakib32\/"}]}},"_links":{"self":[{"href":"https:\/\/www.info-algerie.com\/actualites\/wp-json\/wp\/v2\/posts\/19817","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.info-algerie.com\/actualites\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.info-algerie.com\/actualites\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.info-algerie.com\/actualites\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.info-algerie.com\/actualites\/wp-json\/wp\/v2\/comments?post=19817"}],"version-history":[{"count":0,"href":"https:\/\/www.info-algerie.com\/actualites\/wp-json\/wp\/v2\/posts\/19817\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.info-algerie.com\/actualites\/wp-json\/wp\/v2\/media\/19818"}],"wp:attachment":[{"href":"https:\/\/www.info-algerie.com\/actualites\/wp-json\/wp\/v2\/media?parent=19817"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.info-algerie.com\/actualites\/wp-json\/wp\/v2\/categories?post=19817"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.info-algerie.com\/actualites\/wp-json\/wp\/v2\/tags?post=19817"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}