{"id":23065,"date":"2018-05-07T09:28:54","date_gmt":"2018-05-07T08:28:54","guid":{"rendered":"https:\/\/www.info-algerie.com\/actualites\/lavant-projet-du-decret-de-delegation-de-service-public-soumis-prochainement-au-gouvernement\/"},"modified":"2018-05-07T09:28:54","modified_gmt":"2018-05-07T08:28:54","slug":"lavant-projet-du-decret-de-delegation-de-service-public-soumis-prochainement-au-gouvernement","status":"publish","type":"post","link":"https:\/\/www.info-algerie.com\/actualites\/lavant-projet-du-decret-de-delegation-de-service-public-soumis-prochainement-au-gouvernement\/","title":{"rendered":"L\u2019avant projet du d\u00e9cret de d\u00e9l\u00e9gation de service public, soumis prochainement au Gouvernement"},"content":{"rendered":"<div class=\"K2FeedImage\"><img decoding=\"async\" src=\"https:\/\/www.info-algerie.com\/actualites\/wp-content\/uploads\/2018\/05\/104b83fa7442a3e59ff3ccdb82fd981c_S.jpg\" alt=\"L&#x2019;avant projet du d&#xE9;cret de d&#xE9;l&#xE9;gation de service public, soumis prochainement au Gouvernement\" \/><\/div>\n<div class=\"K2FeedIntroText\">\n<p>SETIF-\u00a0 Le ministre de l\u2019Int\u00e9rieur, des Collectivit\u00e9s locales et l\u2019Am\u00e9nagement du territoire a indiqu\u00e9 dimanche soir \u00e0 S\u00e9tif que l\u2019avant projet du d\u00e9cret fixant les modalit\u00e9s de D\u00e9l\u00e9gation de service public (DSP), un mode de gestion impliquant le priv\u00e9 dans la gestion des infrastructures de base, \u00ab\u00a0sera soumis dans les prochaines semaines au Gouvernement\u00a0\u00bb.<\/p>\n<p>&#013;\n<\/p><\/div>\n<div class=\"K2FeedFullText\">&#013;<\/p>\n<blockquote><p>&#013;<\/p>\n<p><em><strong>Au cours d\u2019une rencontre avec les repr\u00e9sentants de la soci\u00e9t\u00e9 civile et les cadres de la wilaya, tenue \u00e0 l\u2019universit\u00e9 Ferhat Abbas, dans le cadre de sa visite de travail de trois jours,\u00a0 le ministre a pr\u00e9cis\u00e9 que ce d\u00e9cret est en mesure d\u2019assurer aux collectivit\u00e9s \u00ab\u00a0un mode de gestion moderne, garant du d\u00e9veloppement \u00e9conomique\u00a0\u00bb.<\/strong><\/em><\/p>\n<p>&#013;\n<\/p><\/blockquote>\n<p>&#013;<\/p>\n<p>Il a dans ce sens ajout\u00e9 que les\u00a0 probl\u00e8mes dont font face les communes, le manque de revenus\u00a0 et les d\u00e9ficits budg\u00e9taires enregistr\u00e9s par beaucoup d\u2019entre elles \u00ab\u00a0rendaient n\u00e9cessaire le recours\u00a0 \u00e0\u00a0 un mode de gestion moderne bas\u00e9 sur un partenariat public-priv\u00e9 au\u00a0 service du citoyen\u00a0\u00bb.<\/p>\n<p>&#013;<\/p>\n<hr \/>\n<p><a href=\"http:\/\/www.aps.dz\/algerie\/73625-l-algerie-est-arrivee-a-la-mise-a-niveau-des-divers-secteurs-de-developpement\">\u00a0Lire aussi: L\u2019Alg\u00e9rie est arriv\u00e9e \u00e0 la mise \u00e0 niveau des divers secteurs de d\u00e9veloppement<\/a><\/p>\n<p>&#013;<\/p>\n<hr \/>\n<p>Le ministre de l\u2019Int\u00e9rieur, des Collectivit\u00e9s locales et l\u2019Am\u00e9nagement du territoire a consid\u00e9r\u00e9 qu\u2019un mode de gestion moderne offre \u00ab\u00a0des nouvelles perspectives pour les jeunes en mati\u00e8re d\u2019emploi et permet\u00a0 l\u2019 exploitation des centaines d\u2019infrastructures publiques non exploit\u00e9es\u00a0\u00bb.<\/p>\n<p>&#013;<\/p>\n<blockquote><p>&#013;<\/p>\n<p><em><strong>Soulignant\u00a0 qu'\u00a0\u00bbil est de la responsabilit\u00e9 des gestionnaires locaux d\u2019\u00e9difier une \u00e9conomie locale forte et cr\u00e9atrice de richesses et de plus-value\u00a0\u00bb, le ministre a relev\u00e9 que chaque collectivit\u00e9\u00a0 dispose \u00ab\u00a0de\u00a0potentialit\u00e9s de d\u00e9veloppement qui n\u2019attendent que des initiatives et des strat\u00e9gies capables de les rentabiliser\u00a0\u00bb.<\/strong><\/em><\/p>\n<p>&#013;\n<\/p><\/blockquote>\n<p>&#013;<\/p>\n<p>Pr\u00e9sentant la wilaya de S\u00e9tif comme\u00a0 une \u2018\u2018r\u00e9f\u00e9rence\u2019\u2019 dans le d\u00e9veloppement \u00e9conomique, le ministre a soutenu que le Fonds des hauts plateaux que le pr\u00e9sident de la R\u00e9publique, Abdelaziz Bouteflika a ordonn\u00e9 son activation et le programme du gouvernement relatif au d\u00e9veloppement des\u00a0r\u00e9gions montagneuses\u00a0 sont en mesure de permettre \u00e0 S\u00e9tif \u00ab\u00a0d\u2019occuper les premiers rangs dans la nouvelle r\u00e9organisation administrative\u00a0\u00bb.<\/p>\n<p>&#013;<\/p>\n<p>Des pr\u00e9occupations en rapport avec les secteurs de l\u2019agriculture, la sant\u00e9 et le transport ont constitu\u00e9 l\u2019essentiel des th\u00e8mes soulev\u00e9es par les repr\u00e9sentants de la soci\u00e9t\u00e9 civile de S\u00e9tif.<\/p>\n<p>&#013;<\/p>\n<p>Auparavant\u00a0 M.\u00a0 Bedoui avait honor\u00e9\u00a0 dans une c\u00e9r\u00e9monie tenue au chef lieu de wilaya, les moudjahidine, Mohamed Cherif Djenadi, Yakoub Aldjia et Guerfoudj\u00a0 Menouar.<\/p>\n<p>&#013;<\/p>\n<p>Au deuxi\u00e8me jour sa visite dans la wilaya de S\u00e9tif, le ministre de l\u2019Int\u00e9rieur, des collectivit\u00e9s locales et de l\u2019Am\u00e9nagement du territoire devra lancer depuis la commune A\u00efn Legradj le projet de dotation en eau potable de six communes du nord de S\u00e9tif \u00e0 partir du barrage de Tichy Haf (Bejaia) avant d\u2019inspecter le projet de r\u00e9habilitation de la maison du cheikh Fodil El Ouratilani.<\/p>\n<\/div>\n<p>&#013;<br \/>\nSource: <a href=\"http:\/\/www.aps.dz\/algerie\/73630-l-avant-projet-du-decret-de-delegation-de-service-public-soumis-prochainement-au-gouvernement\" target=\"_blank\">L\u2019avant projet du d\u00e9cret de d\u00e9l\u00e9gation de service public, soumis prochainement au Gouvernement<\/a><\/p>\n<!--CusAds0-->\n<div style=\"font-size: 0px; height: 0px; line-height: 0px; margin: 0; padding: 0; clear: both;\"><\/div>","protected":false},"excerpt":{"rendered":"<p>SETIF-\u00a0 Le ministre de l\u2019Int\u00e9rieur, des Collectivit\u00e9s locales et l\u2019Am\u00e9nagement du territoire a indiqu\u00e9 dimanche soir \u00e0 S\u00e9tif que l\u2019avant projet du d\u00e9cret fixant les modalit\u00e9s de D\u00e9l\u00e9gation de service public (DSP), un mode de gestion impliquant le priv\u00e9 dans la gestion des infrastructures de base, \u00ab\u00a0sera soumis dans les prochaines semaines au Gouvernement\u00a0\u00bb. &#013;<\/p>\n","protected":false},"author":6,"featured_media":23066,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22],"tags":[93],"class_list":["post-23065","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-infos","tag-onu"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>L\u2019avant projet du d\u00e9cret de d\u00e9l\u00e9gation de service public, soumis prochainement au Gouvernement - info algerie<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.info-algerie.com\/actualites\/lavant-projet-du-decret-de-delegation-de-service-public-soumis-prochainement-au-gouvernement\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L\u2019avant projet du d\u00e9cret de d\u00e9l\u00e9gation de service public, soumis prochainement au Gouvernement - info algerie\" \/>\n<meta property=\"og:description\" content=\"SETIF-\u00a0 Le ministre de l\u2019Int\u00e9rieur, des Collectivit\u00e9s locales et l\u2019Am\u00e9nagement du territoire a indiqu\u00e9 dimanche soir \u00e0 S\u00e9tif que l\u2019avant projet du d\u00e9cret fixant les modalit\u00e9s de D\u00e9l\u00e9gation de service public (DSP), un mode de gestion impliquant le priv\u00e9 dans la gestion des infrastructures de base, \u00ab\u00a0sera soumis dans les prochaines semaines au Gouvernement\u00a0\u00bb. &#013;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.info-algerie.com\/actualites\/lavant-projet-du-decret-de-delegation-de-service-public-soumis-prochainement-au-gouvernement\/\" \/>\n<meta property=\"og:site_name\" content=\"info algerie\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/infoalgerieactu\" \/>\n<meta property=\"article:published_time\" content=\"2018-05-07T08:28:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.info-algerie.com\/actualites\/wp-content\/uploads\/2018\/05\/104b83fa7442a3e59ff3ccdb82fd981c_S-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"280\" \/>\n\t<meta property=\"og:image:height\" content=\"186\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"La r\u00e9daction\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"La r\u00e9daction\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.info-algerie.com\\\/actualites\\\/lavant-projet-du-decret-de-delegation-de-service-public-soumis-prochainement-au-gouvernement\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.info-algerie.com\\\/actualites\\\/lavant-projet-du-decret-de-delegation-de-service-public-soumis-prochainement-au-gouvernement\\\/\"},\"author\":{\"name\":\"La r\u00e9daction\",\"@id\":\"https:\\\/\\\/www.info-algerie.com\\\/actualites\\\/#\\\/schema\\\/person\\\/847aaec44920825b843a08f30ec6aa1e\"},\"headline\":\"L\u2019avant projet du d\u00e9cret de d\u00e9l\u00e9gation de service public, soumis prochainement au Gouvernement\",\"datePublished\":\"2018-05-07T08:28:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.info-algerie.com\\\/actualites\\\/lavant-projet-du-decret-de-delegation-de-service-public-soumis-prochainement-au-gouvernement\\\/\"},\"wordCount\":541,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.info-algerie.com\\\/actualites\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.info-algerie.com\\\/actualites\\\/lavant-projet-du-decret-de-delegation-de-service-public-soumis-prochainement-au-gouvernement\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.info-algerie.com\\\/actualites\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/104b83fa7442a3e59ff3ccdb82fd981c_S-1.jpg\",\"keywords\":[\"ONU\"],\"articleSection\":[\"infos\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.info-algerie.com\\\/actualites\\\/lavant-projet-du-decret-de-delegation-de-service-public-soumis-prochainement-au-gouvernement\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.info-algerie.com\\\/actualites\\\/lavant-projet-du-decret-de-delegation-de-service-public-soumis-prochainement-au-gouvernement\\\/\",\"url\":\"https:\\\/\\\/www.info-algerie.com\\\/actualites\\\/lavant-projet-du-decret-de-delegation-de-service-public-soumis-prochainement-au-gouvernement\\\/\",\"name\":\"L\u2019avant projet du d\u00e9cret de d\u00e9l\u00e9gation de service public, soumis prochainement au Gouvernement - info algerie\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.info-algerie.com\\\/actualites\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.info-algerie.com\\\/actualites\\\/lavant-projet-du-decret-de-delegation-de-service-public-soumis-prochainement-au-gouvernement\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.info-algerie.com\\\/actualites\\\/lavant-projet-du-decret-de-delegation-de-service-public-soumis-prochainement-au-gouvernement\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.info-algerie.com\\\/actualites\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/104b83fa7442a3e59ff3ccdb82fd981c_S-1.jpg\",\"datePublished\":\"2018-05-07T08:28:54+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.info-algerie.com\\\/actualites\\\/lavant-projet-du-decret-de-delegation-de-service-public-soumis-prochainement-au-gouvernement\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.info-algerie.com\\\/actualites\\\/lavant-projet-du-decret-de-delegation-de-service-public-soumis-prochainement-au-gouvernement\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.info-algerie.com\\\/actualites\\\/lavant-projet-du-decret-de-delegation-de-service-public-soumis-prochainement-au-gouvernement\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.info-algerie.com\\\/actualites\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/104b83fa7442a3e59ff3ccdb82fd981c_S-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.info-algerie.com\\\/actualites\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/104b83fa7442a3e59ff3ccdb82fd981c_S-1.jpg\",\"width\":280,\"height\":186},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.info-algerie.com\\\/actualites\\\/lavant-projet-du-decret-de-delegation-de-service-public-soumis-prochainement-au-gouvernement\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.info-algerie.com\\\/actualites\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L\u2019avant projet du d\u00e9cret de d\u00e9l\u00e9gation de service public, soumis prochainement au Gouvernement\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.info-algerie.com\\\/actualites\\\/#website\",\"url\":\"https:\\\/\\\/www.info-algerie.com\\\/actualites\\\/\",\"name\":\"info algerie\",\"description\":\"Toutes les actualit\u00e9s\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.info-algerie.com\\\/actualites\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.info-algerie.com\\\/actualites\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.info-algerie.com\\\/actualites\\\/#organization\",\"name\":\"info algerie\",\"url\":\"https:\\\/\\\/www.info-algerie.com\\\/actualites\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.info-algerie.com\\\/actualites\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.info-algerie.com\\\/actualites\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/logo-ia-120.png\",\"contentUrl\":\"https:\\\/\\\/www.info-algerie.com\\\/actualites\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/logo-ia-120.png\",\"width\":120,\"height\":43,\"caption\":\"info algerie\"},\"image\":{\"@id\":\"https:\\\/\\\/www.info-algerie.com\\\/actualites\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/infoalgerieactu\",\"https:\\\/\\\/x.com\\\/infoalgerie1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.info-algerie.com\\\/actualites\\\/#\\\/schema\\\/person\\\/847aaec44920825b843a08f30ec6aa1e\",\"name\":\"La r\u00e9daction\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/769db425c6f465158149f1ffd6cf61ce7a8a879d11dfbef8288af36dfddd418c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/769db425c6f465158149f1ffd6cf61ce7a8a879d11dfbef8288af36dfddd418c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/769db425c6f465158149f1ffd6cf61ce7a8a879d11dfbef8288af36dfddd418c?s=96&d=mm&r=g\",\"caption\":\"La r\u00e9daction\"},\"sameAs\":[\"http:\\\/\\\/www.lkeria.com\\\/\"],\"url\":\"https:\\\/\\\/www.info-algerie.com\\\/actualites\\\/author\\\/chakib32\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L\u2019avant projet du d\u00e9cret de d\u00e9l\u00e9gation de service public, soumis prochainement au Gouvernement - info algerie","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.info-algerie.com\/actualites\/lavant-projet-du-decret-de-delegation-de-service-public-soumis-prochainement-au-gouvernement\/","og_locale":"fr_FR","og_type":"article","og_title":"L\u2019avant projet du d\u00e9cret de d\u00e9l\u00e9gation de service public, soumis prochainement au Gouvernement - info algerie","og_description":"SETIF-\u00a0 Le ministre de l\u2019Int\u00e9rieur, des Collectivit\u00e9s locales et l\u2019Am\u00e9nagement du territoire a indiqu\u00e9 dimanche soir \u00e0 S\u00e9tif que l\u2019avant projet du d\u00e9cret fixant les modalit\u00e9s de D\u00e9l\u00e9gation de service public (DSP), un mode de gestion impliquant le priv\u00e9 dans la gestion des infrastructures de base, \u00ab\u00a0sera soumis dans les prochaines semaines au Gouvernement\u00a0\u00bb. &#013;","og_url":"https:\/\/www.info-algerie.com\/actualites\/lavant-projet-du-decret-de-delegation-de-service-public-soumis-prochainement-au-gouvernement\/","og_site_name":"info algerie","article_publisher":"https:\/\/www.facebook.com\/infoalgerieactu","article_published_time":"2018-05-07T08:28:54+00:00","og_image":[{"width":280,"height":186,"url":"https:\/\/www.info-algerie.com\/actualites\/wp-content\/uploads\/2018\/05\/104b83fa7442a3e59ff3ccdb82fd981c_S-1.jpg","type":"image\/jpeg"}],"author":"La r\u00e9daction","twitter_misc":{"\u00c9crit par":"La r\u00e9daction","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.info-algerie.com\/actualites\/lavant-projet-du-decret-de-delegation-de-service-public-soumis-prochainement-au-gouvernement\/#article","isPartOf":{"@id":"https:\/\/www.info-algerie.com\/actualites\/lavant-projet-du-decret-de-delegation-de-service-public-soumis-prochainement-au-gouvernement\/"},"author":{"name":"La r\u00e9daction","@id":"https:\/\/www.info-algerie.com\/actualites\/#\/schema\/person\/847aaec44920825b843a08f30ec6aa1e"},"headline":"L\u2019avant projet du d\u00e9cret de d\u00e9l\u00e9gation de service public, soumis prochainement au Gouvernement","datePublished":"2018-05-07T08:28:54+00:00","mainEntityOfPage":{"@id":"https:\/\/www.info-algerie.com\/actualites\/lavant-projet-du-decret-de-delegation-de-service-public-soumis-prochainement-au-gouvernement\/"},"wordCount":541,"commentCount":0,"publisher":{"@id":"https:\/\/www.info-algerie.com\/actualites\/#organization"},"image":{"@id":"https:\/\/www.info-algerie.com\/actualites\/lavant-projet-du-decret-de-delegation-de-service-public-soumis-prochainement-au-gouvernement\/#primaryimage"},"thumbnailUrl":"https:\/\/www.info-algerie.com\/actualites\/wp-content\/uploads\/2018\/05\/104b83fa7442a3e59ff3ccdb82fd981c_S-1.jpg","keywords":["ONU"],"articleSection":["infos"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.info-algerie.com\/actualites\/lavant-projet-du-decret-de-delegation-de-service-public-soumis-prochainement-au-gouvernement\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.info-algerie.com\/actualites\/lavant-projet-du-decret-de-delegation-de-service-public-soumis-prochainement-au-gouvernement\/","url":"https:\/\/www.info-algerie.com\/actualites\/lavant-projet-du-decret-de-delegation-de-service-public-soumis-prochainement-au-gouvernement\/","name":"L\u2019avant projet du d\u00e9cret de d\u00e9l\u00e9gation de service public, soumis prochainement au Gouvernement - info algerie","isPartOf":{"@id":"https:\/\/www.info-algerie.com\/actualites\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.info-algerie.com\/actualites\/lavant-projet-du-decret-de-delegation-de-service-public-soumis-prochainement-au-gouvernement\/#primaryimage"},"image":{"@id":"https:\/\/www.info-algerie.com\/actualites\/lavant-projet-du-decret-de-delegation-de-service-public-soumis-prochainement-au-gouvernement\/#primaryimage"},"thumbnailUrl":"https:\/\/www.info-algerie.com\/actualites\/wp-content\/uploads\/2018\/05\/104b83fa7442a3e59ff3ccdb82fd981c_S-1.jpg","datePublished":"2018-05-07T08:28:54+00:00","breadcrumb":{"@id":"https:\/\/www.info-algerie.com\/actualites\/lavant-projet-du-decret-de-delegation-de-service-public-soumis-prochainement-au-gouvernement\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.info-algerie.com\/actualites\/lavant-projet-du-decret-de-delegation-de-service-public-soumis-prochainement-au-gouvernement\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.info-algerie.com\/actualites\/lavant-projet-du-decret-de-delegation-de-service-public-soumis-prochainement-au-gouvernement\/#primaryimage","url":"https:\/\/www.info-algerie.com\/actualites\/wp-content\/uploads\/2018\/05\/104b83fa7442a3e59ff3ccdb82fd981c_S-1.jpg","contentUrl":"https:\/\/www.info-algerie.com\/actualites\/wp-content\/uploads\/2018\/05\/104b83fa7442a3e59ff3ccdb82fd981c_S-1.jpg","width":280,"height":186},{"@type":"BreadcrumbList","@id":"https:\/\/www.info-algerie.com\/actualites\/lavant-projet-du-decret-de-delegation-de-service-public-soumis-prochainement-au-gouvernement\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.info-algerie.com\/actualites\/"},{"@type":"ListItem","position":2,"name":"L\u2019avant projet du d\u00e9cret de d\u00e9l\u00e9gation de service public, soumis prochainement au Gouvernement"}]},{"@type":"WebSite","@id":"https:\/\/www.info-algerie.com\/actualites\/#website","url":"https:\/\/www.info-algerie.com\/actualites\/","name":"info algerie","description":"Toutes les actualit\u00e9s","publisher":{"@id":"https:\/\/www.info-algerie.com\/actualites\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.info-algerie.com\/actualites\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.info-algerie.com\/actualites\/#organization","name":"info algerie","url":"https:\/\/www.info-algerie.com\/actualites\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.info-algerie.com\/actualites\/#\/schema\/logo\/image\/","url":"https:\/\/www.info-algerie.com\/actualites\/wp-content\/uploads\/2022\/07\/logo-ia-120.png","contentUrl":"https:\/\/www.info-algerie.com\/actualites\/wp-content\/uploads\/2022\/07\/logo-ia-120.png","width":120,"height":43,"caption":"info algerie"},"image":{"@id":"https:\/\/www.info-algerie.com\/actualites\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/infoalgerieactu","https:\/\/x.com\/infoalgerie1"]},{"@type":"Person","@id":"https:\/\/www.info-algerie.com\/actualites\/#\/schema\/person\/847aaec44920825b843a08f30ec6aa1e","name":"La r\u00e9daction","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/769db425c6f465158149f1ffd6cf61ce7a8a879d11dfbef8288af36dfddd418c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/769db425c6f465158149f1ffd6cf61ce7a8a879d11dfbef8288af36dfddd418c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/769db425c6f465158149f1ffd6cf61ce7a8a879d11dfbef8288af36dfddd418c?s=96&d=mm&r=g","caption":"La r\u00e9daction"},"sameAs":["http:\/\/www.lkeria.com\/"],"url":"https:\/\/www.info-algerie.com\/actualites\/author\/chakib32\/"}]}},"_links":{"self":[{"href":"https:\/\/www.info-algerie.com\/actualites\/wp-json\/wp\/v2\/posts\/23065","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.info-algerie.com\/actualites\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.info-algerie.com\/actualites\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.info-algerie.com\/actualites\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.info-algerie.com\/actualites\/wp-json\/wp\/v2\/comments?post=23065"}],"version-history":[{"count":0,"href":"https:\/\/www.info-algerie.com\/actualites\/wp-json\/wp\/v2\/posts\/23065\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.info-algerie.com\/actualites\/wp-json\/wp\/v2\/media\/23066"}],"wp:attachment":[{"href":"https:\/\/www.info-algerie.com\/actualites\/wp-json\/wp\/v2\/media?parent=23065"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.info-algerie.com\/actualites\/wp-json\/wp\/v2\/categories?post=23065"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.info-algerie.com\/actualites\/wp-json\/wp\/v2\/tags?post=23065"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}