{"id":2938,"date":"2016-03-13T09:01:39","date_gmt":"2016-03-13T08:01:39","guid":{"rendered":"http:\/\/www.info-algerie.com\/actualites\/plus-de-60-000-eleves-suivent-leurs-etudes-dans-des-ecoles-privee\/"},"modified":"2016-03-13T09:01:39","modified_gmt":"2016-03-13T08:01:39","slug":"plus-de-60-000-eleves-suivent-leurs-etudes-dans-des-ecoles-privee","status":"publish","type":"post","link":"https:\/\/www.info-algerie.com\/actualites\/plus-de-60-000-eleves-suivent-leurs-etudes-dans-des-ecoles-privee\/","title":{"rendered":"Plus de 60.000 \u00e9l\u00e8ves suivent leurs \u00e9tudes dans des \u00e9coles priv\u00e9e"},"content":{"rendered":"<div class=\"K2FeedImage\"><img decoding=\"async\" src=\"\" alt=\"Plus de 60.000 &#xE9;l&#xE8;ves suivent leurs &#xE9;tudes dans des &#xE9;coles priv&#xE9;e\" \/><\/div>\n<div class=\"K2FeedIntroText\"> TLEMCEN &#8211; Plus de 60.000 \u00e9l\u00e8ves suivent leurs \u00e9tudes dans des \u00e9coles priv\u00e9es, a-t-on appris samedi \u00e0 Tlemcen du pr\u00e9sident de l\u2019Association nationale des \u00e9coles priv\u00e9es agr\u00e9\u00e9es, Salim Ait Ameur. Cet effectif, qui ne repr\u00e9sente qu&rsquo;un (1) pour cent des effectifs des \u00e9l\u00e8ves scolaris\u00e9s (8 millions), sont r\u00e9partis sur 320\u2026<\/div>\n<p>&#013;<br \/>\nSource: <a href=\"http:\/\/www.aps.dz\/algerie\/38385-plus-de-60-000-%C3%A9l%C3%A8ves-suivent-leurs-%C3%A9tudes-dans-des-%C3%A9coles-priv%C3%A9e\" target=\"_blank\">Plus de 60.000 \u00e9l\u00e8ves suivent leurs \u00e9tudes dans des \u00e9coles priv\u00e9e<\/a><\/p>\n<!--CusAds0-->\n<div style=\"font-size: 0px; height: 0px; line-height: 0px; margin: 0; padding: 0; clear: both;\"><\/div>","protected":false},"excerpt":{"rendered":"<p>TLEMCEN &#8211; Plus de 60.000 \u00e9l\u00e8ves suivent leurs \u00e9tudes dans des \u00e9coles priv\u00e9es, a-t-on appris samedi \u00e0 Tlemcen du pr\u00e9sident de l\u2019Association nationale des \u00e9coles priv\u00e9es agr\u00e9\u00e9es, Salim Ait Ameur. Cet effectif, qui ne repr\u00e9sente qu&rsquo;un (1) pour cent des effectifs des \u00e9l\u00e8ves scolaris\u00e9s (8 millions), sont r\u00e9partis sur 320\u2026 &#013; Source: Plus de 60.000<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22],"tags":[93],"class_list":["post-2938","post","type-post","status-publish","format-standard","hentry","category-infos","tag-onu"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Plus de 60.000 \u00e9l\u00e8ves suivent leurs \u00e9tudes dans des \u00e9coles priv\u00e9e - info algerie<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.info-algerie.com\/actualites\/plus-de-60-000-eleves-suivent-leurs-etudes-dans-des-ecoles-privee\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Plus de 60.000 \u00e9l\u00e8ves suivent leurs \u00e9tudes dans des \u00e9coles priv\u00e9e - info algerie\" \/>\n<meta property=\"og:description\" content=\"TLEMCEN &#8211; Plus de 60.000 \u00e9l\u00e8ves suivent leurs \u00e9tudes dans des \u00e9coles priv\u00e9es, a-t-on appris samedi \u00e0 Tlemcen du pr\u00e9sident de l\u2019Association nationale des \u00e9coles priv\u00e9es agr\u00e9\u00e9es, Salim Ait Ameur. Cet effectif, qui ne repr\u00e9sente qu&rsquo;un (1) pour cent des effectifs des \u00e9l\u00e8ves scolaris\u00e9s (8 millions), sont r\u00e9partis sur 320\u2026 &#013; Source: Plus de 60.000\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.info-algerie.com\/actualites\/plus-de-60-000-eleves-suivent-leurs-etudes-dans-des-ecoles-privee\/\" \/>\n<meta property=\"og:site_name\" content=\"info algerie\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/infoalgerieactu\" \/>\n<meta property=\"article:published_time\" content=\"2016-03-13T08:01:39+00:00\" \/>\n<meta name=\"author\" content=\"La r\u00e9daction\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"La r\u00e9daction\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.info-algerie.com\\\/actualites\\\/plus-de-60-000-eleves-suivent-leurs-etudes-dans-des-ecoles-privee\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.info-algerie.com\\\/actualites\\\/plus-de-60-000-eleves-suivent-leurs-etudes-dans-des-ecoles-privee\\\/\"},\"author\":{\"name\":\"La r\u00e9daction\",\"@id\":\"https:\\\/\\\/www.info-algerie.com\\\/actualites\\\/#\\\/schema\\\/person\\\/847aaec44920825b843a08f30ec6aa1e\"},\"headline\":\"Plus de 60.000 \u00e9l\u00e8ves suivent leurs \u00e9tudes dans des \u00e9coles priv\u00e9e\",\"datePublished\":\"2016-03-13T08:01:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.info-algerie.com\\\/actualites\\\/plus-de-60-000-eleves-suivent-leurs-etudes-dans-des-ecoles-privee\\\/\"},\"wordCount\":81,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.info-algerie.com\\\/actualites\\\/#organization\"},\"keywords\":[\"ONU\"],\"articleSection\":[\"infos\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.info-algerie.com\\\/actualites\\\/plus-de-60-000-eleves-suivent-leurs-etudes-dans-des-ecoles-privee\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.info-algerie.com\\\/actualites\\\/plus-de-60-000-eleves-suivent-leurs-etudes-dans-des-ecoles-privee\\\/\",\"url\":\"https:\\\/\\\/www.info-algerie.com\\\/actualites\\\/plus-de-60-000-eleves-suivent-leurs-etudes-dans-des-ecoles-privee\\\/\",\"name\":\"Plus de 60.000 \u00e9l\u00e8ves suivent leurs \u00e9tudes dans des \u00e9coles priv\u00e9e - info algerie\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.info-algerie.com\\\/actualites\\\/#website\"},\"datePublished\":\"2016-03-13T08:01:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.info-algerie.com\\\/actualites\\\/plus-de-60-000-eleves-suivent-leurs-etudes-dans-des-ecoles-privee\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.info-algerie.com\\\/actualites\\\/plus-de-60-000-eleves-suivent-leurs-etudes-dans-des-ecoles-privee\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.info-algerie.com\\\/actualites\\\/plus-de-60-000-eleves-suivent-leurs-etudes-dans-des-ecoles-privee\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.info-algerie.com\\\/actualites\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Plus de 60.000 \u00e9l\u00e8ves suivent leurs \u00e9tudes dans des \u00e9coles priv\u00e9e\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.info-algerie.com\\\/actualites\\\/#website\",\"url\":\"https:\\\/\\\/www.info-algerie.com\\\/actualites\\\/\",\"name\":\"info algerie\",\"description\":\"Toutes les actualit\u00e9s\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.info-algerie.com\\\/actualites\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.info-algerie.com\\\/actualites\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.info-algerie.com\\\/actualites\\\/#organization\",\"name\":\"info algerie\",\"url\":\"https:\\\/\\\/www.info-algerie.com\\\/actualites\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.info-algerie.com\\\/actualites\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.info-algerie.com\\\/actualites\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/logo-ia-120.png\",\"contentUrl\":\"https:\\\/\\\/www.info-algerie.com\\\/actualites\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/logo-ia-120.png\",\"width\":120,\"height\":43,\"caption\":\"info algerie\"},\"image\":{\"@id\":\"https:\\\/\\\/www.info-algerie.com\\\/actualites\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/infoalgerieactu\",\"https:\\\/\\\/x.com\\\/infoalgerie1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.info-algerie.com\\\/actualites\\\/#\\\/schema\\\/person\\\/847aaec44920825b843a08f30ec6aa1e\",\"name\":\"La r\u00e9daction\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/769db425c6f465158149f1ffd6cf61ce7a8a879d11dfbef8288af36dfddd418c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/769db425c6f465158149f1ffd6cf61ce7a8a879d11dfbef8288af36dfddd418c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/769db425c6f465158149f1ffd6cf61ce7a8a879d11dfbef8288af36dfddd418c?s=96&d=mm&r=g\",\"caption\":\"La r\u00e9daction\"},\"sameAs\":[\"http:\\\/\\\/www.lkeria.com\\\/\"],\"url\":\"https:\\\/\\\/www.info-algerie.com\\\/actualites\\\/author\\\/chakib32\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Plus de 60.000 \u00e9l\u00e8ves suivent leurs \u00e9tudes dans des \u00e9coles priv\u00e9e - info algerie","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.info-algerie.com\/actualites\/plus-de-60-000-eleves-suivent-leurs-etudes-dans-des-ecoles-privee\/","og_locale":"fr_FR","og_type":"article","og_title":"Plus de 60.000 \u00e9l\u00e8ves suivent leurs \u00e9tudes dans des \u00e9coles priv\u00e9e - info algerie","og_description":"TLEMCEN &#8211; Plus de 60.000 \u00e9l\u00e8ves suivent leurs \u00e9tudes dans des \u00e9coles priv\u00e9es, a-t-on appris samedi \u00e0 Tlemcen du pr\u00e9sident de l\u2019Association nationale des \u00e9coles priv\u00e9es agr\u00e9\u00e9es, Salim Ait Ameur. Cet effectif, qui ne repr\u00e9sente qu&rsquo;un (1) pour cent des effectifs des \u00e9l\u00e8ves scolaris\u00e9s (8 millions), sont r\u00e9partis sur 320\u2026 &#013; Source: Plus de 60.000","og_url":"https:\/\/www.info-algerie.com\/actualites\/plus-de-60-000-eleves-suivent-leurs-etudes-dans-des-ecoles-privee\/","og_site_name":"info algerie","article_publisher":"https:\/\/www.facebook.com\/infoalgerieactu","article_published_time":"2016-03-13T08:01:39+00:00","author":"La r\u00e9daction","twitter_misc":{"\u00c9crit par":"La r\u00e9daction"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.info-algerie.com\/actualites\/plus-de-60-000-eleves-suivent-leurs-etudes-dans-des-ecoles-privee\/#article","isPartOf":{"@id":"https:\/\/www.info-algerie.com\/actualites\/plus-de-60-000-eleves-suivent-leurs-etudes-dans-des-ecoles-privee\/"},"author":{"name":"La r\u00e9daction","@id":"https:\/\/www.info-algerie.com\/actualites\/#\/schema\/person\/847aaec44920825b843a08f30ec6aa1e"},"headline":"Plus de 60.000 \u00e9l\u00e8ves suivent leurs \u00e9tudes dans des \u00e9coles priv\u00e9e","datePublished":"2016-03-13T08:01:39+00:00","mainEntityOfPage":{"@id":"https:\/\/www.info-algerie.com\/actualites\/plus-de-60-000-eleves-suivent-leurs-etudes-dans-des-ecoles-privee\/"},"wordCount":81,"commentCount":0,"publisher":{"@id":"https:\/\/www.info-algerie.com\/actualites\/#organization"},"keywords":["ONU"],"articleSection":["infos"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.info-algerie.com\/actualites\/plus-de-60-000-eleves-suivent-leurs-etudes-dans-des-ecoles-privee\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.info-algerie.com\/actualites\/plus-de-60-000-eleves-suivent-leurs-etudes-dans-des-ecoles-privee\/","url":"https:\/\/www.info-algerie.com\/actualites\/plus-de-60-000-eleves-suivent-leurs-etudes-dans-des-ecoles-privee\/","name":"Plus de 60.000 \u00e9l\u00e8ves suivent leurs \u00e9tudes dans des \u00e9coles priv\u00e9e - info algerie","isPartOf":{"@id":"https:\/\/www.info-algerie.com\/actualites\/#website"},"datePublished":"2016-03-13T08:01:39+00:00","breadcrumb":{"@id":"https:\/\/www.info-algerie.com\/actualites\/plus-de-60-000-eleves-suivent-leurs-etudes-dans-des-ecoles-privee\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.info-algerie.com\/actualites\/plus-de-60-000-eleves-suivent-leurs-etudes-dans-des-ecoles-privee\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.info-algerie.com\/actualites\/plus-de-60-000-eleves-suivent-leurs-etudes-dans-des-ecoles-privee\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.info-algerie.com\/actualites\/"},{"@type":"ListItem","position":2,"name":"Plus de 60.000 \u00e9l\u00e8ves suivent leurs \u00e9tudes dans des \u00e9coles priv\u00e9e"}]},{"@type":"WebSite","@id":"https:\/\/www.info-algerie.com\/actualites\/#website","url":"https:\/\/www.info-algerie.com\/actualites\/","name":"info algerie","description":"Toutes les actualit\u00e9s","publisher":{"@id":"https:\/\/www.info-algerie.com\/actualites\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.info-algerie.com\/actualites\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.info-algerie.com\/actualites\/#organization","name":"info algerie","url":"https:\/\/www.info-algerie.com\/actualites\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.info-algerie.com\/actualites\/#\/schema\/logo\/image\/","url":"https:\/\/www.info-algerie.com\/actualites\/wp-content\/uploads\/2022\/07\/logo-ia-120.png","contentUrl":"https:\/\/www.info-algerie.com\/actualites\/wp-content\/uploads\/2022\/07\/logo-ia-120.png","width":120,"height":43,"caption":"info algerie"},"image":{"@id":"https:\/\/www.info-algerie.com\/actualites\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/infoalgerieactu","https:\/\/x.com\/infoalgerie1"]},{"@type":"Person","@id":"https:\/\/www.info-algerie.com\/actualites\/#\/schema\/person\/847aaec44920825b843a08f30ec6aa1e","name":"La r\u00e9daction","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/769db425c6f465158149f1ffd6cf61ce7a8a879d11dfbef8288af36dfddd418c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/769db425c6f465158149f1ffd6cf61ce7a8a879d11dfbef8288af36dfddd418c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/769db425c6f465158149f1ffd6cf61ce7a8a879d11dfbef8288af36dfddd418c?s=96&d=mm&r=g","caption":"La r\u00e9daction"},"sameAs":["http:\/\/www.lkeria.com\/"],"url":"https:\/\/www.info-algerie.com\/actualites\/author\/chakib32\/"}]}},"_links":{"self":[{"href":"https:\/\/www.info-algerie.com\/actualites\/wp-json\/wp\/v2\/posts\/2938","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.info-algerie.com\/actualites\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.info-algerie.com\/actualites\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.info-algerie.com\/actualites\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.info-algerie.com\/actualites\/wp-json\/wp\/v2\/comments?post=2938"}],"version-history":[{"count":0,"href":"https:\/\/www.info-algerie.com\/actualites\/wp-json\/wp\/v2\/posts\/2938\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.info-algerie.com\/actualites\/wp-json\/wp\/v2\/media?parent=2938"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.info-algerie.com\/actualites\/wp-json\/wp\/v2\/categories?post=2938"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.info-algerie.com\/actualites\/wp-json\/wp\/v2\/tags?post=2938"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}