{"id":4667,"date":"2016-05-03T15:21:04","date_gmt":"2016-05-03T14:21:04","guid":{"rendered":"http:\/\/www.info-algerie.com\/actualites\/les-directeurs-de-leducation-et-des-etablissements-libres-de-fixer-la-date-des-compositions\/"},"modified":"2016-05-03T15:21:04","modified_gmt":"2016-05-03T14:21:04","slug":"les-directeurs-de-leducation-et-des-etablissements-libres-de-fixer-la-date-des-compositions","status":"publish","type":"post","link":"https:\/\/www.info-algerie.com\/actualites\/les-directeurs-de-leducation-et-des-etablissements-libres-de-fixer-la-date-des-compositions\/","title":{"rendered":"Les directeurs de l&#039;\u00e9ducation et des \u00e9tablissements libres de fixer la date des compositions"},"content":{"rendered":"<div class=\"K2FeedImage\"><img decoding=\"async\" src=\"https:\/\/www.info-algerie.com\/actualites\/wp-content\/uploads\/2016\/05\/4a17f7177a87f5071b4681a4b6fe2ab3_S.jpg\" alt=\"Les directeurs de l'&#xE9;ducation et des &#xE9;tablissements libres de fixer la date des compositions\" \/><\/div>\n<div class=\"K2FeedIntroText\"> ALGER- La ministre de l&rsquo;Education nationale, Nouria Benghebrit, a affirm\u00e9 mardi \u00e0 Alger, que le minist\u00e8re laissait la libert\u00e9 aux directeurs de l&rsquo;\u00e9ducation et directeurs des \u00e9tablissements \u00e9ducatifs de fixer la date des compositions du troisi\u00e8me trimestre. Dans une d\u00e9claration \u00e0 la presse apr\u00e8s avoir supervis\u00e9 le d\u00e9but des examens\u2026<\/div>\n<p>&#013;<br \/>\nSource: <a href=\"http:\/\/www.aps.dz\/algerie\/41550-les-directeurs-de-l-%C3%A9ducation-et-des-%C3%A9tablissements-libres-de-fixer-la-date-des-compositions\" target=\"_blank\">Les directeurs de l&rsquo;\u00e9ducation et des \u00e9tablissements libres de fixer la date des compositions<\/a><\/p>\n<!--CusAds0-->\n<div style=\"font-size: 0px; height: 0px; line-height: 0px; margin: 0; padding: 0; clear: both;\"><\/div>","protected":false},"excerpt":{"rendered":"<p>ALGER- La ministre de l&rsquo;Education nationale, Nouria Benghebrit, a affirm\u00e9 mardi \u00e0 Alger, que le minist\u00e8re laissait la libert\u00e9 aux directeurs de l&rsquo;\u00e9ducation et directeurs des \u00e9tablissements \u00e9ducatifs de fixer la date des compositions du troisi\u00e8me trimestre. Dans une d\u00e9claration \u00e0 la presse apr\u00e8s avoir supervis\u00e9 le d\u00e9but des examens\u2026 &#013; Source: Les directeurs de<\/p>\n","protected":false},"author":6,"featured_media":4668,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22],"tags":[93],"class_list":["post-4667","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-infos","tag-onu"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Les directeurs de l&#039;\u00e9ducation et des \u00e9tablissements libres de fixer la date des compositions - info algerie<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.info-algerie.com\/actualites\/les-directeurs-de-leducation-et-des-etablissements-libres-de-fixer-la-date-des-compositions\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les directeurs de l&#039;\u00e9ducation et des \u00e9tablissements libres de fixer la date des compositions - info algerie\" \/>\n<meta property=\"og:description\" content=\"ALGER- La ministre de l&rsquo;Education nationale, Nouria Benghebrit, a affirm\u00e9 mardi \u00e0 Alger, que le minist\u00e8re laissait la libert\u00e9 aux directeurs de l&rsquo;\u00e9ducation et directeurs des \u00e9tablissements \u00e9ducatifs de fixer la date des compositions du troisi\u00e8me trimestre. Dans une d\u00e9claration \u00e0 la presse apr\u00e8s avoir supervis\u00e9 le d\u00e9but des examens\u2026 &#013; Source: Les directeurs de\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.info-algerie.com\/actualites\/les-directeurs-de-leducation-et-des-etablissements-libres-de-fixer-la-date-des-compositions\/\" \/>\n<meta property=\"og:site_name\" content=\"info algerie\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/infoalgerieactu\" \/>\n<meta property=\"article:published_time\" content=\"2016-05-03T14:21:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.info-algerie.com\/actualites\/wp-content\/uploads\/2016\/05\/4a17f7177a87f5071b4681a4b6fe2ab3_S-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"150\" \/>\n\t<meta property=\"og:image:height\" content=\"99\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"La r\u00e9daction\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"La r\u00e9daction\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.info-algerie.com\\\/actualites\\\/les-directeurs-de-leducation-et-des-etablissements-libres-de-fixer-la-date-des-compositions\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.info-algerie.com\\\/actualites\\\/les-directeurs-de-leducation-et-des-etablissements-libres-de-fixer-la-date-des-compositions\\\/\"},\"author\":{\"name\":\"La r\u00e9daction\",\"@id\":\"https:\\\/\\\/www.info-algerie.com\\\/actualites\\\/#\\\/schema\\\/person\\\/847aaec44920825b843a08f30ec6aa1e\"},\"headline\":\"Les directeurs de l&#039;\u00e9ducation et des \u00e9tablissements libres de fixer la date des compositions\",\"datePublished\":\"2016-05-03T14:21:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.info-algerie.com\\\/actualites\\\/les-directeurs-de-leducation-et-des-etablissements-libres-de-fixer-la-date-des-compositions\\\/\"},\"wordCount\":86,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.info-algerie.com\\\/actualites\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.info-algerie.com\\\/actualites\\\/les-directeurs-de-leducation-et-des-etablissements-libres-de-fixer-la-date-des-compositions\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.info-algerie.com\\\/actualites\\\/wp-content\\\/uploads\\\/2016\\\/05\\\/4a17f7177a87f5071b4681a4b6fe2ab3_S-1.jpg\",\"keywords\":[\"ONU\"],\"articleSection\":[\"infos\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.info-algerie.com\\\/actualites\\\/les-directeurs-de-leducation-et-des-etablissements-libres-de-fixer-la-date-des-compositions\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.info-algerie.com\\\/actualites\\\/les-directeurs-de-leducation-et-des-etablissements-libres-de-fixer-la-date-des-compositions\\\/\",\"url\":\"https:\\\/\\\/www.info-algerie.com\\\/actualites\\\/les-directeurs-de-leducation-et-des-etablissements-libres-de-fixer-la-date-des-compositions\\\/\",\"name\":\"Les directeurs de l&#039;\u00e9ducation et des \u00e9tablissements libres de fixer la date des compositions - info algerie\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.info-algerie.com\\\/actualites\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.info-algerie.com\\\/actualites\\\/les-directeurs-de-leducation-et-des-etablissements-libres-de-fixer-la-date-des-compositions\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.info-algerie.com\\\/actualites\\\/les-directeurs-de-leducation-et-des-etablissements-libres-de-fixer-la-date-des-compositions\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.info-algerie.com\\\/actualites\\\/wp-content\\\/uploads\\\/2016\\\/05\\\/4a17f7177a87f5071b4681a4b6fe2ab3_S-1.jpg\",\"datePublished\":\"2016-05-03T14:21:04+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.info-algerie.com\\\/actualites\\\/les-directeurs-de-leducation-et-des-etablissements-libres-de-fixer-la-date-des-compositions\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.info-algerie.com\\\/actualites\\\/les-directeurs-de-leducation-et-des-etablissements-libres-de-fixer-la-date-des-compositions\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.info-algerie.com\\\/actualites\\\/les-directeurs-de-leducation-et-des-etablissements-libres-de-fixer-la-date-des-compositions\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.info-algerie.com\\\/actualites\\\/wp-content\\\/uploads\\\/2016\\\/05\\\/4a17f7177a87f5071b4681a4b6fe2ab3_S-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.info-algerie.com\\\/actualites\\\/wp-content\\\/uploads\\\/2016\\\/05\\\/4a17f7177a87f5071b4681a4b6fe2ab3_S-1.jpg\",\"width\":150,\"height\":99},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.info-algerie.com\\\/actualites\\\/les-directeurs-de-leducation-et-des-etablissements-libres-de-fixer-la-date-des-compositions\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.info-algerie.com\\\/actualites\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les directeurs de l&#039;\u00e9ducation et des \u00e9tablissements libres de fixer la date des compositions\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.info-algerie.com\\\/actualites\\\/#website\",\"url\":\"https:\\\/\\\/www.info-algerie.com\\\/actualites\\\/\",\"name\":\"info algerie\",\"description\":\"Toutes les actualit\u00e9s\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.info-algerie.com\\\/actualites\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.info-algerie.com\\\/actualites\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.info-algerie.com\\\/actualites\\\/#organization\",\"name\":\"info algerie\",\"url\":\"https:\\\/\\\/www.info-algerie.com\\\/actualites\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.info-algerie.com\\\/actualites\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.info-algerie.com\\\/actualites\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/logo-ia-120.png\",\"contentUrl\":\"https:\\\/\\\/www.info-algerie.com\\\/actualites\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/logo-ia-120.png\",\"width\":120,\"height\":43,\"caption\":\"info algerie\"},\"image\":{\"@id\":\"https:\\\/\\\/www.info-algerie.com\\\/actualites\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/infoalgerieactu\",\"https:\\\/\\\/x.com\\\/infoalgerie1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.info-algerie.com\\\/actualites\\\/#\\\/schema\\\/person\\\/847aaec44920825b843a08f30ec6aa1e\",\"name\":\"La r\u00e9daction\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/769db425c6f465158149f1ffd6cf61ce7a8a879d11dfbef8288af36dfddd418c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/769db425c6f465158149f1ffd6cf61ce7a8a879d11dfbef8288af36dfddd418c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/769db425c6f465158149f1ffd6cf61ce7a8a879d11dfbef8288af36dfddd418c?s=96&d=mm&r=g\",\"caption\":\"La r\u00e9daction\"},\"sameAs\":[\"http:\\\/\\\/www.lkeria.com\\\/\"],\"url\":\"https:\\\/\\\/www.info-algerie.com\\\/actualites\\\/author\\\/chakib32\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Les directeurs de l&#039;\u00e9ducation et des \u00e9tablissements libres de fixer la date des compositions - info algerie","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.info-algerie.com\/actualites\/les-directeurs-de-leducation-et-des-etablissements-libres-de-fixer-la-date-des-compositions\/","og_locale":"fr_FR","og_type":"article","og_title":"Les directeurs de l&#039;\u00e9ducation et des \u00e9tablissements libres de fixer la date des compositions - info algerie","og_description":"ALGER- La ministre de l&rsquo;Education nationale, Nouria Benghebrit, a affirm\u00e9 mardi \u00e0 Alger, que le minist\u00e8re laissait la libert\u00e9 aux directeurs de l&rsquo;\u00e9ducation et directeurs des \u00e9tablissements \u00e9ducatifs de fixer la date des compositions du troisi\u00e8me trimestre. Dans une d\u00e9claration \u00e0 la presse apr\u00e8s avoir supervis\u00e9 le d\u00e9but des examens\u2026 &#013; Source: Les directeurs de","og_url":"https:\/\/www.info-algerie.com\/actualites\/les-directeurs-de-leducation-et-des-etablissements-libres-de-fixer-la-date-des-compositions\/","og_site_name":"info algerie","article_publisher":"https:\/\/www.facebook.com\/infoalgerieactu","article_published_time":"2016-05-03T14:21:04+00:00","og_image":[{"width":150,"height":99,"url":"https:\/\/www.info-algerie.com\/actualites\/wp-content\/uploads\/2016\/05\/4a17f7177a87f5071b4681a4b6fe2ab3_S-1.jpg","type":"image\/jpeg"}],"author":"La r\u00e9daction","twitter_misc":{"\u00c9crit par":"La r\u00e9daction"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.info-algerie.com\/actualites\/les-directeurs-de-leducation-et-des-etablissements-libres-de-fixer-la-date-des-compositions\/#article","isPartOf":{"@id":"https:\/\/www.info-algerie.com\/actualites\/les-directeurs-de-leducation-et-des-etablissements-libres-de-fixer-la-date-des-compositions\/"},"author":{"name":"La r\u00e9daction","@id":"https:\/\/www.info-algerie.com\/actualites\/#\/schema\/person\/847aaec44920825b843a08f30ec6aa1e"},"headline":"Les directeurs de l&#039;\u00e9ducation et des \u00e9tablissements libres de fixer la date des compositions","datePublished":"2016-05-03T14:21:04+00:00","mainEntityOfPage":{"@id":"https:\/\/www.info-algerie.com\/actualites\/les-directeurs-de-leducation-et-des-etablissements-libres-de-fixer-la-date-des-compositions\/"},"wordCount":86,"commentCount":0,"publisher":{"@id":"https:\/\/www.info-algerie.com\/actualites\/#organization"},"image":{"@id":"https:\/\/www.info-algerie.com\/actualites\/les-directeurs-de-leducation-et-des-etablissements-libres-de-fixer-la-date-des-compositions\/#primaryimage"},"thumbnailUrl":"https:\/\/www.info-algerie.com\/actualites\/wp-content\/uploads\/2016\/05\/4a17f7177a87f5071b4681a4b6fe2ab3_S-1.jpg","keywords":["ONU"],"articleSection":["infos"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.info-algerie.com\/actualites\/les-directeurs-de-leducation-et-des-etablissements-libres-de-fixer-la-date-des-compositions\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.info-algerie.com\/actualites\/les-directeurs-de-leducation-et-des-etablissements-libres-de-fixer-la-date-des-compositions\/","url":"https:\/\/www.info-algerie.com\/actualites\/les-directeurs-de-leducation-et-des-etablissements-libres-de-fixer-la-date-des-compositions\/","name":"Les directeurs de l&#039;\u00e9ducation et des \u00e9tablissements libres de fixer la date des compositions - info algerie","isPartOf":{"@id":"https:\/\/www.info-algerie.com\/actualites\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.info-algerie.com\/actualites\/les-directeurs-de-leducation-et-des-etablissements-libres-de-fixer-la-date-des-compositions\/#primaryimage"},"image":{"@id":"https:\/\/www.info-algerie.com\/actualites\/les-directeurs-de-leducation-et-des-etablissements-libres-de-fixer-la-date-des-compositions\/#primaryimage"},"thumbnailUrl":"https:\/\/www.info-algerie.com\/actualites\/wp-content\/uploads\/2016\/05\/4a17f7177a87f5071b4681a4b6fe2ab3_S-1.jpg","datePublished":"2016-05-03T14:21:04+00:00","breadcrumb":{"@id":"https:\/\/www.info-algerie.com\/actualites\/les-directeurs-de-leducation-et-des-etablissements-libres-de-fixer-la-date-des-compositions\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.info-algerie.com\/actualites\/les-directeurs-de-leducation-et-des-etablissements-libres-de-fixer-la-date-des-compositions\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.info-algerie.com\/actualites\/les-directeurs-de-leducation-et-des-etablissements-libres-de-fixer-la-date-des-compositions\/#primaryimage","url":"https:\/\/www.info-algerie.com\/actualites\/wp-content\/uploads\/2016\/05\/4a17f7177a87f5071b4681a4b6fe2ab3_S-1.jpg","contentUrl":"https:\/\/www.info-algerie.com\/actualites\/wp-content\/uploads\/2016\/05\/4a17f7177a87f5071b4681a4b6fe2ab3_S-1.jpg","width":150,"height":99},{"@type":"BreadcrumbList","@id":"https:\/\/www.info-algerie.com\/actualites\/les-directeurs-de-leducation-et-des-etablissements-libres-de-fixer-la-date-des-compositions\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.info-algerie.com\/actualites\/"},{"@type":"ListItem","position":2,"name":"Les directeurs de l&#039;\u00e9ducation et des \u00e9tablissements libres de fixer la date des compositions"}]},{"@type":"WebSite","@id":"https:\/\/www.info-algerie.com\/actualites\/#website","url":"https:\/\/www.info-algerie.com\/actualites\/","name":"info algerie","description":"Toutes les actualit\u00e9s","publisher":{"@id":"https:\/\/www.info-algerie.com\/actualites\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.info-algerie.com\/actualites\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.info-algerie.com\/actualites\/#organization","name":"info algerie","url":"https:\/\/www.info-algerie.com\/actualites\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.info-algerie.com\/actualites\/#\/schema\/logo\/image\/","url":"https:\/\/www.info-algerie.com\/actualites\/wp-content\/uploads\/2022\/07\/logo-ia-120.png","contentUrl":"https:\/\/www.info-algerie.com\/actualites\/wp-content\/uploads\/2022\/07\/logo-ia-120.png","width":120,"height":43,"caption":"info algerie"},"image":{"@id":"https:\/\/www.info-algerie.com\/actualites\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/infoalgerieactu","https:\/\/x.com\/infoalgerie1"]},{"@type":"Person","@id":"https:\/\/www.info-algerie.com\/actualites\/#\/schema\/person\/847aaec44920825b843a08f30ec6aa1e","name":"La r\u00e9daction","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/769db425c6f465158149f1ffd6cf61ce7a8a879d11dfbef8288af36dfddd418c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/769db425c6f465158149f1ffd6cf61ce7a8a879d11dfbef8288af36dfddd418c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/769db425c6f465158149f1ffd6cf61ce7a8a879d11dfbef8288af36dfddd418c?s=96&d=mm&r=g","caption":"La r\u00e9daction"},"sameAs":["http:\/\/www.lkeria.com\/"],"url":"https:\/\/www.info-algerie.com\/actualites\/author\/chakib32\/"}]}},"_links":{"self":[{"href":"https:\/\/www.info-algerie.com\/actualites\/wp-json\/wp\/v2\/posts\/4667","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.info-algerie.com\/actualites\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.info-algerie.com\/actualites\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.info-algerie.com\/actualites\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.info-algerie.com\/actualites\/wp-json\/wp\/v2\/comments?post=4667"}],"version-history":[{"count":0,"href":"https:\/\/www.info-algerie.com\/actualites\/wp-json\/wp\/v2\/posts\/4667\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.info-algerie.com\/actualites\/wp-json\/wp\/v2\/media\/4668"}],"wp:attachment":[{"href":"https:\/\/www.info-algerie.com\/actualites\/wp-json\/wp\/v2\/media?parent=4667"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.info-algerie.com\/actualites\/wp-json\/wp\/v2\/categories?post=4667"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.info-algerie.com\/actualites\/wp-json\/wp\/v2\/tags?post=4667"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}